{"id":25471,"date":"2024-06-05T10:13:49","date_gmt":"2024-06-05T07:13:49","guid":{"rendered":"https:\/\/marmarayerelhizmet.com\/?p=25471"},"modified":"2024-06-05T10:13:49","modified_gmt":"2024-06-05T07:13:49","slug":"nazim-hikmet-ismi-kultur-merkezine-verildi","status":"publish","type":"post","link":"https:\/\/marmarayerelhizmet.com\/index.php\/2024\/06\/05\/nazim-hikmet-ismi-kultur-merkezine-verildi\/","title":{"rendered":"Naz\u0131m Hikmet ismi K\u00fclt\u00fcr Merkezi\u2019ne Verildi"},"content":{"rendered":"<p><strong><span style=\"font-family: arial, helvetica, sans-serif; font-size: 14px;\">Esenyurt\u2019ta 21 y\u0131l \u00f6nce ismi Esenyurt K\u00fclt\u00fcr Merkezi olarak de\u011fi\u015ftirilen Naz\u0131m Hikmet K\u00fclt\u00fcr Merkezi\u2019ne yeniden \u015eair Naz\u0131m Hikmet Ran\u2019\u0131n ismi \u00f6l\u00fcm\u00fcn\u00fcn 61. y\u0131l d\u00f6n\u00fcm\u00fcnde d\u00fczenlenen t\u00f6renle verildi.<br \/>\n<\/span><\/strong><br \/>\n<span style=\"font-family: arial, helvetica, sans-serif; font-size: 14px;\">Esenyurt Belediyesi taraf\u0131ndan \u015eair Naz\u0131m Hikmet Ran\u2019\u0131n ismi d\u00fczenlenen t\u00f6ren ile Esenyurt K\u00fclt\u00fcr Merkezi\u2019ne verildi. 21 y\u0131l \u00f6nce de Naz\u0131m Hikmet K\u00fclt\u00fcr Merkezi olan yap\u0131n\u0131n ismi de\u011fi\u015ftirilmi\u015f ve tabelas\u0131 Esenyurt K\u00fclt\u00fcr Merkezi olarak as\u0131lm\u0131\u015ft\u0131. \u015eair Naz\u0131m Hikmet Ran\u2019\u0131n \u00f6l\u00fcm\u00fcn\u00fcn 61. y\u0131l d\u00f6n\u00fcm\u00fcnde d\u00fczenlenen programa Esenyurt Belediye Ba\u015fkan\u0131 Ahmet \u00d6zer ve bir\u00e7ok vatanda\u015f kat\u0131ld\u0131. K\u00fcrs\u00fcye \u00e7\u0131karak konu\u015fma yapan Ba\u015fkan \u00d6zer, K\u00fclt\u00fcr Merkezi \u00f6n\u00fcnde bulunan Naz\u0131m Hikmet B\u00fcst\u00fc\u2019n\u00fcn \u00f6n\u00fcne \u00e7i\u00e7ek b\u0131rakt\u0131. Tabela a\u00e7\u0131l\u0131\u015f\u0131 sonras\u0131 Naz\u0131m Hikmet Park\u0131\u2019nda ise \u015eair Naz\u0131m Hikmet i\u00e7in anma t\u00f6reni ger\u00e7ekle\u015ftirildi. T\u00f6ren sonras\u0131nda K\u00fclt\u00fcr Merkezi\u2019nde anma etkinlikleri kapsam\u0131nda y\u00f6netmen ve gazeteci Nebil \u00d6zgent\u00fcrk ile s\u00f6yle\u015fi, belgesel g\u00f6sterimi, \u015fiir ve m\u00fczik dinletisi yap\u0131ld\u0131.<\/span><\/p>\n<p><strong><span style=\"font-family: arial, helvetica, sans-serif; font-size: 14px;\">\u201cMottomuz Esenyurt\u2019u k\u00fclt\u00fcr ve sanat ba\u015fkenti haline getirmektir\u201d<\/span><\/strong><br \/>\n<span style=\"font-family: arial, helvetica, sans-serif; font-size: 14px;\">T\u00f6rende konu\u015fan Esenyurt Belediye Ba\u015fkan\u0131 Ahmet \u00d6zer, \u201cBug\u00fcn burada \u00f6l\u00fcms\u00fcz ozan, de\u011ferli ozan\u0131m\u0131z, de\u011ferli \u015fairimiz Naz\u0131m Hikmet Ran\u2019\u0131n ad\u0131n\u0131 verdi\u011fimiz k\u00fclt\u00fcr merkezini a\u00e7t\u0131k. Daha \u00f6nce bu ad buradan s\u00f6k\u00fclm\u00fc\u015ft\u00fc ve kullan\u0131lm\u0131yordu. Oysa \u00fclkeler, beldeler, memleketler, o \u00fclkelerden, o beldelerden, o memleketlerden yeti\u015fmi\u015f b\u00fcy\u00fck insanlar\u0131n adlar\u0131yla an\u0131l\u0131rlar. Bug\u00fcn d\u00fcnyada Naz\u0131m Hikmet denilince T\u00fcrkiye, T\u00fcrkiye denilince Naz\u0131m Hikmet akla geliyor. Ahmet Arif, Orhan Kemal, Ya\u015far Kemal akla geliyor. Bunlar hayatlar\u0131 boyunca hep mazlumdan yana zalime kar\u015f\u0131 durmu\u015f. Kalemleriyle, yaz\u0131lar\u0131yla, \u015fiirleriyle bu m\u00fccadeleyi s\u00fcrd\u00fcrm\u00fc\u015f olan insanlard\u0131r. Bizim de onlara sayg\u0131 borcumuz var. Onlar bizim y\u00fcre\u011fimizde \u00f6nemli bir tarih bilincidirler. Biz bug\u00fcn g\u00f6reve geldi\u011fimizin ikinci ay\u0131nda bu yanl\u0131\u015f\u0131 k\u00f6k\u00fcnden d\u00fczelttik. Bundan sonra Naz\u0131m Hikmet K\u00fclt\u00fcr Merkezi\u2019mizde k\u00fclt\u00fcr ve sanat faaliyetlerimizi s\u00fcrd\u00fcrece\u011fiz. Geldi\u011fimiz g\u00fcnden beri s\u00f6yl\u00fcyoruz. Esenyurt\u2019umuzun k\u00fclt\u00fcre, sanata \u00e7ok b\u00fcy\u00fck ihtiyac\u0131 var. Mottomuz Esenyurt\u2019u k\u00fclt\u00fcr ve sanat ba\u015fkenti haline getirmektir. Bunu da Naz\u0131m Hikmet\u2019lerin merkezleriyle, Ya\u015far Kemal\u2019lerin k\u00fct\u00fcphaneleriyle, Ahmet Arif\u2019lerin \u015fiir etkinlikleriyle yapaca\u011f\u0131z ve bug\u00fcn buradan ba\u015flad\u0131k. Esenyurt\u2019umuza hay\u0131rl\u0131 ve u\u011furlu olsun\u201d dedi.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esenyurt\u2019ta 21 y\u0131l \u00f6nce ismi Esenyurt K\u00fclt\u00fcr Merkezi olarak de\u011fi\u015ftirilen Naz\u0131m Hikmet K\u00fclt\u00fcr Merkezi\u2019ne yeniden \u015eair Naz\u0131m Hikmet Ran\u2019\u0131n ismi<\/p>\n","protected":false},"author":3,"featured_media":25472,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1,5,6,8],"tags":[],"class_list":["post-25471","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-genel","category-gundem","category-kultur-sanat","category-siyaset"],"_links":{"self":[{"href":"https:\/\/marmarayerelhizmet.com\/index.php\/wp-json\/wp\/v2\/posts\/25471","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marmarayerelhizmet.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/marmarayerelhizmet.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/marmarayerelhizmet.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/marmarayerelhizmet.com\/index.php\/wp-json\/wp\/v2\/comments?post=25471"}],"version-history":[{"count":0,"href":"https:\/\/marmarayerelhizmet.com\/index.php\/wp-json\/wp\/v2\/posts\/25471\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/marmarayerelhizmet.com\/index.php\/wp-json\/wp\/v2\/media\/25472"}],"wp:attachment":[{"href":"https:\/\/marmarayerelhizmet.com\/index.php\/wp-json\/wp\/v2\/media?parent=25471"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/marmarayerelhizmet.com\/index.php\/wp-json\/wp\/v2\/categories?post=25471"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/marmarayerelhizmet.com\/index.php\/wp-json\/wp\/v2\/tags?post=25471"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}